{"id":584,"date":"2019-11-22T14:54:29","date_gmt":"2019-11-22T13:54:29","guid":{"rendered":"https:\/\/courdesvosges.com\/dev\/univers\/"},"modified":"2021-12-23T11:31:44","modified_gmt":"2021-12-23T10:31:44","slug":"5-star-luxury-hotel-marais","status":"publish","type":"page","link":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/","title":{"rendered":"Universe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":19,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-univers.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-584","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5-star luxury hotel Marais (Paris) - View on the Place des Vosges<\/title>\n<meta name=\"description\" content=\"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5-star luxury hotel Marais (Paris) - View on the Place des Vosges\" \/>\n<meta property=\"og:description\" content=\"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/\" \/>\n<meta property=\"og:site_name\" content=\"COUR DES VOSGES\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-23T10:31:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/courdesvosges.com\\\/en\\\/5-star-luxury-hotel-marais\\\/\",\"url\":\"https:\\\/\\\/courdesvosges.com\\\/en\\\/5-star-luxury-hotel-marais\\\/\",\"name\":\"5-star luxury hotel Marais (Paris) - View on the Place des Vosges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/courdesvosges.com\\\/#website\"},\"datePublished\":\"2019-11-22T13:54:29+00:00\",\"dateModified\":\"2021-12-23T10:31:44+00:00\",\"description\":\"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/courdesvosges.com\\\/en\\\/5-star-luxury-hotel-marais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/courdesvosges.com\\\/en\\\/5-star-luxury-hotel-marais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/courdesvosges.com\\\/en\\\/5-star-luxury-hotel-marais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/courdesvosges.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/courdesvosges.com\\\/#website\",\"url\":\"https:\\\/\\\/courdesvosges.com\\\/\",\"name\":\"COUR DES VOSGES\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/courdesvosges.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5-star luxury hotel Marais (Paris) - View on the Place des Vosges","description":"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/","og_locale":"en_US","og_type":"article","og_title":"5-star luxury hotel Marais (Paris) - View on the Place des Vosges","og_description":"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!","og_url":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/","og_site_name":"COUR DES VOSGES","article_modified_time":"2021-12-23T10:31:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/","url":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/","name":"5-star luxury hotel Marais (Paris) - View on the Place des Vosges","isPartOf":{"@id":"https:\/\/courdesvosges.com\/#website"},"datePublished":"2019-11-22T13:54:29+00:00","dateModified":"2021-12-23T10:31:44+00:00","description":"COUR DES VOSGES (Evok H\u00f4tels Collection) - A confidential place, between history and design: a unique 5-star luxury hotel with a view of the Place des Vosges (Marais, Paris). Book a room!","breadcrumb":{"@id":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/courdesvosges.com\/en\/5-star-luxury-hotel-marais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/courdesvosges.com\/en\/"},{"@type":"ListItem","position":2,"name":"Universe"}]},{"@type":"WebSite","@id":"https:\/\/courdesvosges.com\/#website","url":"https:\/\/courdesvosges.com\/","name":"COUR DES VOSGES","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/courdesvosges.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/pages\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":28,"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/pages\/584\/revisions"}],"predecessor-version":[{"id":2926,"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/pages\/584\/revisions\/2926"}],"wp:attachment":[{"href":"https:\/\/courdesvosges.com\/en\/wp-json\/wp\/v2\/media?parent=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}